{"id":2121,"date":"2024-05-14T08:49:26","date_gmt":"2024-05-14T11:49:26","guid":{"rendered":"https:\/\/eic.cefet-rj.br\/~eogasawara\/?page_id=2121"},"modified":"2026-08-24T05:49:56","modified_gmt":"2026-08-24T08:49:56","slug":"daltoolbox","status":"publish","type":"page","link":"https:\/\/eic.cefet-rj.br\/~eogasawara\/daltoolbox\/","title":{"rendered":"DAL Toolbox"},"content":{"rendered":"<p><strong>DAL Toolbox<\/strong> \u00e9 um framework em R para organiza\u00e7\u00e3o de workflows de an\u00e1lise de dados. O pacote re\u00fane recursos para pr\u00e9-processamento, classifica\u00e7\u00e3o, regress\u00e3o, agrupamento, minera\u00e7\u00e3o de padr\u00f5es, visualiza\u00e7\u00e3o e constru\u00e7\u00e3o de pipelines anal\u00edticos reprodut\u00edveis.<\/p>\n<p>O material apresenta o <code>daltoolbox<\/code> como apoio para estudos e experimentos em ci\u00eancia de dados, com exemplos organizados de forma progressiva e tem\u00e1tica.<\/p>\n<h3><strong>Material de apoio<\/strong><\/h3>\n<ul>\n<li><a href=\"https:\/\/github.com\/cefet-rj-dal\/daltoolbox\/wiki\">Wiki com documenta\u00e7\u00e3o, exemplos e materiais do pacote<\/a><\/li>\n<\/ul>\n<h3><strong>Playlist do tutorial<br \/>\n<a href=\"https:\/\/www.youtube.com\/playlist?list=PLExOtPNxNUwY\" target=\"_blank\" rel=\"nofollow noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/camo.githubusercontent.com\/be5f7579bfbd708b96135537d8491b8d1e8ebf810734281595411d95a11b5cd4\/68747470733a2f2f696d672e736869656c64732e696f2f62616467652f596f75547562652d5761746368253230706c61796c6973742d7265643f6c6f676f3d796f7574756265266c6f676f436f6c6f723d7768697465\" alt=\"Watch the playlist on YouTube\" width=\"161\" height=\"20\" data-canonical-src=\"https:\/\/img.shields.io\/badge\/YouTube-Watch%20playlist-red?logo=youtube&amp;logoColor=white\" \/><\/a><br \/>\n<\/strong><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>DAL Toolbox \u00e9 um framework em R para organiza\u00e7\u00e3o de workflows de an\u00e1lise de dados. O pacote re\u00fane recursos para pr\u00e9-processamento, classifica\u00e7\u00e3o, regress\u00e3o, agrupamento, minera\u00e7\u00e3o de padr\u00f5es, visualiza\u00e7\u00e3o e constru\u00e7\u00e3o de pipelines anal\u00edticos reprodut\u00edveis. O material apresenta o daltoolbox como apoio para estudos e experimentos em ci\u00eancia de dados, com exemplos organizados de forma progressiva [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2121","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/eic.cefet-rj.br\/~eogasawara\/wp-json\/wp\/v2\/pages\/2121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eic.cefet-rj.br\/~eogasawara\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eic.cefet-rj.br\/~eogasawara\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eic.cefet-rj.br\/~eogasawara\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eic.cefet-rj.br\/~eogasawara\/wp-json\/wp\/v2\/comments?post=2121"}],"version-history":[{"count":16,"href":"https:\/\/eic.cefet-rj.br\/~eogasawara\/wp-json\/wp\/v2\/pages\/2121\/revisions"}],"predecessor-version":[{"id":2790,"href":"https:\/\/eic.cefet-rj.br\/~eogasawara\/wp-json\/wp\/v2\/pages\/2121\/revisions\/2790"}],"wp:attachment":[{"href":"https:\/\/eic.cefet-rj.br\/~eogasawara\/wp-json\/wp\/v2\/media?parent=2121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}