{"id":4035,"date":"2026-05-12T22:53:34","date_gmt":"2026-05-13T01:53:34","guid":{"rendered":"https:\/\/eic.cefet-rj.br\/meninasnarobotica\/?p=4035"},"modified":"2026-05-12T22:53:34","modified_gmt":"2026-05-13T01:53:34","slug":"2a-capacitacao-meninas-na-robotica-2026-alunas-do-cefet-rj","status":"publish","type":"post","link":"https:\/\/eic.cefet-rj.br\/meninasnarobotica\/index.php\/2026\/05\/12\/2a-capacitacao-meninas-na-robotica-2026-alunas-do-cefet-rj\/","title":{"rendered":"2\u00aa Capacita\u00e7\u00e3o Meninas na Rob\u00f3tica 2026 \u2013 Alunas do CEFET\/RJ"},"content":{"rendered":"\n<p>No dia 16 de maio, realizaremos mais um encontro especial do Meninas na Rob\u00f3tica no CEFET\/RJ \u2013 Campus Nova Igua\u00e7u.<\/p>\n\n\n\n<p><strong>A capacita\u00e7\u00e3o ser\u00e1 voltada para as bolsistas de IC e IC-Jr dos campi Nova Igua\u00e7u, Petr\u00f3polis, Maracan\u00e3 e Nova Friburgo, al\u00e9m das alunas volunt\u00e1rias do projeto.<\/strong><\/p>\n\n\n\n<p>Ao longo do encontro, as participantes ter\u00e3o a oportunidade de aprofundar seus conhecimentos por meio de atividades pr\u00e1ticas, desenvolvimento de miniprojetos e troca de experi\u00eancias entre integrantes de diferentes campi.<\/p>\n\n\n\n<p>Mais do que um momento de forma\u00e7\u00e3o t\u00e9cnica, a capacita\u00e7\u00e3o ser\u00e1 um espa\u00e7o de integra\u00e7\u00e3o, aprendizado e fortalecimento da presen\u00e7a feminina na ci\u00eancia e na tecnologia.<\/p>\n\n\n\n<p>Ser\u00e1 mais uma oportunidade para construir conhecimento, compartilhar experi\u00eancias e seguir inspirando cada vez mais meninas a ocuparem seu espa\u00e7o na rob\u00f3tica. \u2728\ud83d\udc9c\ud83d\ude80<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/eic.cefet-rj.br\/meninasnarobotica\/wp-content\/uploads\/2026\/05\/122-1024x576.png\" alt=\"\" class=\"wp-image-4036\" srcset=\"https:\/\/eic.cefet-rj.br\/meninasnarobotica\/wp-content\/uploads\/2026\/05\/122-1024x576.png 1024w, https:\/\/eic.cefet-rj.br\/meninasnarobotica\/wp-content\/uploads\/2026\/05\/122-300x169.png 300w, https:\/\/eic.cefet-rj.br\/meninasnarobotica\/wp-content\/uploads\/2026\/05\/122-768x432.png 768w, https:\/\/eic.cefet-rj.br\/meninasnarobotica\/wp-content\/uploads\/2026\/05\/122-1536x864.png 1536w, https:\/\/eic.cefet-rj.br\/meninasnarobotica\/wp-content\/uploads\/2026\/05\/122.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>No dia 16 de maio, realizaremos mais um encontro especial do Meninas na Rob\u00f3tica no CEFET\/RJ \u2013 Campus Nova Igua\u00e7u. A capacita\u00e7\u00e3o ser\u00e1 voltada para as bolsistas de IC e IC-Jr dos campi Nova Igua\u00e7u, Petr\u00f3polis, Maracan\u00e3 e Nova Friburgo, al\u00e9m das alunas volunt\u00e1rias do projeto. Ao longo do encontro, as participantes ter\u00e3o a oportunidade [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":4038,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-4035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-capacitacao"],"_links":{"self":[{"href":"https:\/\/eic.cefet-rj.br\/meninasnarobotica\/index.php\/wp-json\/wp\/v2\/posts\/4035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eic.cefet-rj.br\/meninasnarobotica\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eic.cefet-rj.br\/meninasnarobotica\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eic.cefet-rj.br\/meninasnarobotica\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eic.cefet-rj.br\/meninasnarobotica\/index.php\/wp-json\/wp\/v2\/comments?post=4035"}],"version-history":[{"count":1,"href":"https:\/\/eic.cefet-rj.br\/meninasnarobotica\/index.php\/wp-json\/wp\/v2\/posts\/4035\/revisions"}],"predecessor-version":[{"id":4039,"href":"https:\/\/eic.cefet-rj.br\/meninasnarobotica\/index.php\/wp-json\/wp\/v2\/posts\/4035\/revisions\/4039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eic.cefet-rj.br\/meninasnarobotica\/index.php\/wp-json\/wp\/v2\/media\/4038"}],"wp:attachment":[{"href":"https:\/\/eic.cefet-rj.br\/meninasnarobotica\/index.php\/wp-json\/wp\/v2\/media?parent=4035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eic.cefet-rj.br\/meninasnarobotica\/index.php\/wp-json\/wp\/v2\/categories?post=4035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eic.cefet-rj.br\/meninasnarobotica\/index.php\/wp-json\/wp\/v2\/tags?post=4035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}